{"id":3253,"count":2,"description":"","link":"https:\/\/seletlumieretv.org\/blogue\/tag\/sainte-couronne-depines","name":"Sainte Couronne d'\u00e9pines","slug":"sainte-couronne-depines","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/seletlumieretv.org\/blogue\/wp-json\/wp\/v2\/tags\/3253"}],"collection":[{"href":"https:\/\/seletlumieretv.org\/blogue\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/seletlumieretv.org\/blogue\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/seletlumieretv.org\/blogue\/wp-json\/wp\/v2\/posts?tags=3253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}